{"id":27748929,"date":"2026-02-11T07:54:04","date_gmt":"2026-02-11T06:54:04","guid":{"rendered":"https:\/\/piano-academy-fritz.com\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\/"},"modified":"2026-03-11T17:29:30","modified_gmt":"2026-03-11T16:29:30","slug":"piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb","status":"publish","type":"page","link":"https:\/\/piano-academy-fritz.com\/ja\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\/","title":{"rendered":"Piano Academy Fritz\u306b\u304a\u3051\u308b\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\u30fb\u30a2\u30af\u30b7\u30e7\u30f3\u8abf\u6574\u30bb\u30df\u30ca\u30fc"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_flex_section section_has_divider et_pb_bottom_divider\">\n<div class=\"et_pb_row_0 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_0 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"dipi_text_highlighter_0 dipi_text_highlighter et_pb_bg_layout_light et_pb_module\"><h2 class=\"dipi-highlight-text-wrapper\" data-config=\"{&quot;animation_start&quot;:&quot;in_a_viewport&quot;,&quot;animation_start_viewport&quot;:&quot;75%&quot;,&quot;animation_delay&quot;:&quot;1000ms&quot;,&quot;animation_duration&quot;:&quot;800ms&quot;,&quot;delay_after_animation&quot;:&quot;3000ms&quot;,&quot;repeat_mode&quot;:&quot;infinite&quot;,&quot;count_mode&quot;:&quot;everytime_in_viewport&quot;,&quot;animation_repeat_counts&quot;:&quot;1&quot;,&quot;reverse_animation&quot;:&quot;off&quot;,&quot;id&quot;:&quot;dipi_text_highlighter_0&quot;}\">\n\t\t\t\t\t<span class=\"dipi-highlight-prefix-text dipi-text-affixes\">\u30a2\u30af\u30b7\u30e7\u30f3\u6539\u8a02\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\u30b3\u30f3\u30b5\u30fc\u30c8\u30b0\u30e9\u30f3\u30c9<\/span><span class=\"dipi-text-highlight-wrapper {&quot;animation_start&quot;:&quot;in_a_viewport&quot;,&quot;animation_start_viewport&quot;:&quot;75%&quot;,&quot;animation_delay&quot;:&quot;1000ms&quot;,&quot;animation_duration&quot;:&quot;800ms&quot;,&quot;delay_after_animation&quot;:&quot;3000ms&quot;,&quot;repeat_mode&quot;:&quot;infinite&quot;,&quot;count_mode&quot;:&quot;everytime_in_viewport&quot;,&quot;animation_repeat_counts&quot;:&quot;1&quot;,&quot;reverse_animation&quot;:&quot;off&quot;,&quot;id&quot;:&quot;dipi_text_highlighter_0&quot;}\"><span class=\"dipi-text-highlight-text dipi-text-highlight-text\">\u30de\u30b9\u30bf\u30fc\u30af\u30e9\u30b9<\/span><span class=\"dipi-text-highlight-svg\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 500 150\" preserveAspectRatio=\"none\"><path d=\"M7.7,145.6C109,125,299.9,116.2,401,121.3c42.1,2.2,87.6,11.8,87.3,25.7\"><\/path><\/svg><\/span><\/span>\n\t\t\t<\/h2><\/div>\n<\/div>\n<\/div>\n<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div><\/div>\n\n<div class=\"et_pb_section_1 et_pb_section et_section_regular et_flex_section section_has_divider et_pb_top_divider et_pb_bottom_divider\" id=\"v2\"><div class=\"et_pb_top_inside_divider et-no-transition\"><\/div>\n<div class=\"et_pb_row_1 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_1 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_image_0 et_pb_image et_animated et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/piano-academy-fritz.com\/wp-content\/uploads\/2026\/02\/Steinway-action-revision.jpg\" title=\"Steinway-action-revision\" width=\"1000\" height=\"1000\" srcset=\"https:\/\/piano-academy-fritz.com\/wp-content\/uploads\/2026\/02\/Steinway-action-revision.jpg 1000w, https:\/\/piano-academy-fritz.com\/wp-content\/uploads\/2026\/02\/Steinway-action-revision-980x980.jpg 980w, https:\/\/piano-academy-fritz.com\/wp-content\/uploads\/2026\/02\/Steinway-action-revision-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" class=\"wp-image-27586873\" \/><\/span><\/div>\n<\/div>\n\n<div class=\"et_pb_column_2 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_16_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module\"><div class=\"et_pb_text_inner\"><h3 style=\"text-align: left;\"><span>\u8a18\u9332\u7684\u306a\u77ed\u6642\u9593\u3067\u30b3\u30f3\u30b5\u30fc\u30c8\u4ed5\u69d8\u306b\uff1a\u59a5\u5354\u306e\u306a\u3044\u512a\u308c\u305f\u30a2\u30af\u30b7\u30e7\u30f3\u30fb\u30e1\u30f3\u30c6\u30ca\u30f3\u30b9<\/span><\/h3>\n<\/div><\/div>\n\n<div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module\"><div class=\"et_pb_text_inner\"><p>\u672c\u30bb\u30df\u30ca\u30fc\u3067\u306f\u3001\u30d4\u30a2\u30ce\u88fd\u9020\u8005\u306b\u3068\u3063\u3066\u30a2\u30d5\u30bf\u30fc\u30b5\u30fc\u30d3\u30b9\u3084\u30b3\u30f3\u30b5\u30fc\u30c8\u30b5\u30fc\u30d3\u30b9\u306b\u304a\u3051\u308b2\u756a\u76ee\u306b\u56f0\u96e3\u306a\u8ab2\u984c\u3067\u3042\u308b\u3001\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\u30fb\u30b0\u30e9\u30f3\u30c9\u30d4\u30a2\u30ce\u306e\u30a2\u30af\u30b7\u30e7\u30f3\u8abf\u6574\u3092\u53d6\u308a\u4e0a\u3052\u307e\u3059\u3002\u901a\u5e38\u3001\u5e74\u306b\u4e00\u5ea6\u884c\u308f\u308c\u308b\u4f5c\u696d\u3067\u3059\u3002  <\/p>\n<p>\u3059\u3079\u3066\u306e\u4f5c\u696d\u3092\u6975\u3081\u3066\u77ed\u6642\u9593\u3067\u5b8c\u4e86\u3055\u305b\u308b\u5fc5\u8981\u304c\u3042\u308a\u3001\u8efd\u5fae\u306a\u4fee\u7406\u3001\u6253\u9375\u97f3\u3084\u305d\u306e\u4ed6\u306e\u554f\u984c\u306e\u89e3\u6d88\u3082\u884c\u308f\u306a\u3051\u308c\u3070\u306a\u308a\u307e\u305b\u3093\u3002\u8981\u6c42\u6c34\u6e96\u306f\u9ad8\u304f\u3001\u6642\u9593\u306f\u5e38\u306b\u4e0d\u8db3\u3057\u3066\u3044\u307e\u3059\u3002\u672c\u8cea\u7684\u306a\u90e8\u5206\u306b\u96c6\u4e2d\u3059\u308b\u3053\u3068\u304c\u4e0d\u53ef\u6b20\u3067\u3059\u3002  <\/p>\n<p>\u3053\u306e\u3088\u3046\u306a\u30c8\u30ec\u30fc\u30cb\u30f3\u30b0\u306f\u307b\u3068\u3093\u3069\u5b58\u5728\u3057\u307e\u305b\u3093\u3002\u30d4\u30a2\u30ce\u88fd\u9020\u8005\u304c\u9867\u5ba2\u30b5\u30fc\u30d3\u30b9\u696d\u52d9\u306b\u5099\u3048\u308b\u3053\u3068\u306f\u91cd\u8981\u3060\u3068\u8003\u3048\u3066\u3044\u307e\u3059\u3002<br \/>\u79c1\u306e\u30bb\u30df\u30ca\u30fc\u3067\u306f\u3001\u96c6\u4e2d\u529b\u3001\u6700\u9069\u306a\u30ea\u30bd\u30fc\u30b9\u914d\u5206\u3001\u30d4\u30a2\u30ce\u30a2\u30af\u30b7\u30e7\u30f3\u3084\u30c8\u30e9\u30c3\u30d7\u30ef\u30fc\u30af\uff08\u30da\u30c0\u30eb\u6a5f\u69cb\uff09\u3001\u7a81\u304d\u4e0a\u3052\u68d2\u30b7\u30b9\u30c6\u30e0\u306b\u304a\u3051\u308b\u7279\u6709\u306e\u96d1\u97f3\u306e\u89e3\u6d88\u3001\u305d\u3057\u3066\u9867\u5ba2\u306e\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\u30fb\u30b0\u30e9\u30f3\u30c9\u30d4\u30a2\u30ce\u306b\u751f\u3058\u308b\u5178\u578b\u7684\u306a\u5909\u5316\u306b\u3064\u3044\u3066\u7db2\u7f85\u3057\u307e\u3059\u3002\u3082\u3061\u308d\u3093\u3001\u6574\u97f3\u6280\u8853\u304c\u65b0\u3057\u3044\u30cf\u30f3\u30de\u30fc\u30d8\u30c3\u30c9\u306e\u6574\u97f3\u3068\u3069\u306e\u3088\u3046\u306b\u7570\u306a\u308b\u306e\u304b\u306b\u3064\u3044\u3066\u3082\u89e3\u8aac\u3057\u307e\u3059\u3002  <\/p>\n<p>\u3053\u306e\u30de\u30b9\u30bf\u30fc\u30af\u30e9\u30b9\u306f\u3001\u8cb4\u5927\u5b66\u3084\u30b3\u30f3\u30b5\u30fc\u30c8\u30db\u30fc\u30eb\u3067\u306e\u5b9f\u65bd\u304c\u6700\u9069\u3067\u3059\u3002<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div><\/div>\n\n<div class=\"et_pb_section_2 et_pb_section et_section_regular et_flex_section section_has_divider et_pb_top_divider et_pb_bottom_divider\" id=\"v2\"><div class=\"et_pb_top_inside_divider et-no-transition\"><\/div>\n<div class=\"et_pb_row_2 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_3 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_heading_0 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h1 class=\"et_pb_module_header\">\u30bb\u30df\u30ca\u30fc\u306b\u3064\u3044\u3066\u77e5\u3063\u3066\u304a\u304f\u3079\u304d\u3053\u3068<\/h1><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_3 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_4 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_8_24_tablet et_flex_column_24_24_phone\">\n<div class=\"dipi_hover_box_0 dipi_hover_box et_pb_module\"><div class=\"dipi-hover-box-container dipi-hover-box-slide-bottom hover_box_align_front_center hover_box_align_back_center\" data-force_square=\"off\">\n                <div class=\"dipi-hover-box-inner-wrapper\">\n                    <div class=\"dipi-hover-box-content\">\n              \n              <div class=\"dipi-hover-box-content-innner\">\n                    <div class=\"dipi-content-image-icon-wrap dipi-icon-wrap\">\n                    <span class=\"et-pb-icon et-pb-font-icon dipi-hover-box-content-icon\">R<\/span>\n                <\/div>\n                    <div class=\"dipi-text\">\n                        <h2 class=\"dipi-hover-box-heading\">\u30bb\u30df\u30ca\u30fc\u306e\u7a2e\u985e<\/h2>\n                        \n                    <\/div>\n              <\/div>\n            <\/div>\n            \n                    <div class=\"dipi-hover-box-hover\">\n                \n                <div class=\"dipi-hover-box-hover-innner\">\n                    \n                    <div class=\"dipi-text\">\n                        \n                        <div class=\"dipi-desc\"><p>\u30c7\u30a3\u30fc\u30d7\u30e9\u30fc\u30cb\u30f3\u30b0\u3068\u3001\u3054\u81ea\u8eab\u306e\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\uff06\u30b5\u30f3\u30ba\u88fd\u30b0\u30e9\u30f3\u30c9\u30d4\u30a2\u30ce\u3092\u4f7f\u3063\u305f\u96c6\u4e2d\u7684\u306a\u5b9f\u8df5\u6f14\u7fd2<\/p><\/div>\n                    <\/div>\n                    <a class=\"et_pb_button dipi-hover-button\" href=\"#\">Learn More<\/a>\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_5 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_8_24_tablet et_flex_column_24_24_phone\">\n<div class=\"dipi_hover_box_1 dipi_hover_box et_pb_module\"><div class=\"dipi-hover-box-container dipi-hover-box-slide-top hover_box_align_front_center hover_box_align_back_center\" data-force_square=\"off\">\n                <div class=\"dipi-hover-box-inner-wrapper\">\n                    <div class=\"dipi-hover-box-content\">\n              \n              <div class=\"dipi-hover-box-content-innner\">\n                    <div class=\"dipi-content-image-icon-wrap dipi-icon-wrap\">\n                    <span class=\"et-pb-icon et-pb-font-icon dipi-hover-box-content-icon\">\ue023<\/span>\n                <\/div>\n                    <div class=\"dipi-text\">\n                        <h2 class=\"dipi-hover-box-heading\">\u671f\u9593<\/h2>\n                        \n                    <\/div>\n              <\/div>\n            <\/div>\n            \n                    <div class=\"dipi-hover-box-hover\">\n                \n                <div class=\"dipi-hover-box-hover-innner\">\n                    \n                    <div class=\"dipi-text\">\n                        \n                        <div class=\"dipi-desc\"><p>5\u65e5\u9593<\/p><\/div>\n                    <\/div>\n                    <a class=\"et_pb_button dipi-hover-button\" href=\"#\">Learn More<\/a>\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_6 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_8_24_tablet et_flex_column_24_24_phone\">\n<div class=\"dipi_hover_box_2 dipi_hover_box et_pb_module\"><div class=\"dipi-hover-box-container dipi-hover-box-slide-top hover_box_align_front_center hover_box_align_back_center\" data-force_square=\"off\">\n                <div class=\"dipi-hover-box-inner-wrapper\">\n                    <div class=\"dipi-hover-box-content\">\n              \n              <div class=\"dipi-hover-box-content-innner\">\n                    <div class=\"dipi-content-image-icon-wrap dipi-icon-wrap\">\n                    <span class=\"et-pb-icon et-pb-font-icon dipi-hover-box-content-icon\">\ue01d<\/span>\n                <\/div>\n                    <div class=\"dipi-text\">\n                        <h2 class=\"dipi-hover-box-heading\">\u6240\u5728\u5730<\/h2>\n                        \n                    <\/div>\n              <\/div>\n            <\/div>\n            \n                    <div class=\"dipi-hover-box-hover\">\n                \n                <div class=\"dipi-hover-box-hover-innner\">\n                    \n                    <div class=\"dipi-text\">\n                        \n                        <div class=\"dipi-desc\"><p>\u30d9\u30eb\u30ea\u30f3\uff06\u30dd\u30eb\u30c8\u30ac\u30eb \u30b3\u30f3\u30b5\u30fc\u30c8\u4f1a\u5834\uff06\u3042\u306a\u305f\u306e\u97f3\u697d\u5927\u5b66<\/p><\/div>\n                    <\/div>\n                    <a class=\"et_pb_button dipi-hover-button\" href=\"#\">Learn More<\/a>\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_4 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_7 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_8_24_tablet et_flex_column_24_24_phone\">\n<div class=\"dipi_hover_box_3 dipi_hover_box et_pb_module\"><div class=\"dipi-hover-box-container dipi-hover-box-slide-top hover_box_align_front_center hover_box_align_back_center\" data-force_square=\"off\">\n                <div class=\"dipi-hover-box-inner-wrapper\">\n                    <div class=\"dipi-hover-box-content\">\n              \n              <div class=\"dipi-hover-box-content-innner\">\n                    <div class=\"dipi-content-image-icon-wrap dipi-icon-wrap\">\n                    <span class=\"et-pb-icon et-pb-font-icon dipi-hover-box-content-icon\">\ue036<\/span>\n                <\/div>\n                    <div class=\"dipi-text\">\n                        <h2 class=\"dipi-hover-box-heading\">\u30b9\u30da\u30a2\u30d1\u30fc\u30c4<\/h2>\n                        \n                    <\/div>\n              <\/div>\n            <\/div>\n            \n                    <div class=\"dipi-hover-box-hover\">\n                \n                <div class=\"dipi-hover-box-hover-innner\">\n                    \n                    <div class=\"dipi-text\">\n                        \n                        <div class=\"dipi-desc\"><p>Steinway damper heads with wires.<\/p>\n<p>Spare parts price on request.<span class=\"Y2IQFc\" lang=\"en\"><\/span><\/p><\/div>\n                    <\/div>\n                    <a class=\"et_pb_button dipi-hover-button\" href=\"#\">Learn More<\/a>\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_8 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_8_24_tablet et_flex_column_24_24_phone\">\n<div class=\"dipi_hover_box_4 dipi_hover_box et_pb_module\"><div class=\"dipi-hover-box-container dipi-hover-box-slide-top hover_box_align_front_center hover_box_align_back_center\" data-force_square=\"off\">\n                <div class=\"dipi-hover-box-inner-wrapper\">\n                    <div class=\"dipi-hover-box-content\">\n              \n              <div class=\"dipi-hover-box-content-innner\">\n                    <div class=\"dipi-content-image-icon-wrap dipi-icon-wrap\">\n                    <span class=\"et-pb-icon et-pb-font-icon dipi-hover-box-content-icon\">\uf0c0<\/span>\n                <\/div>\n                    <div class=\"dipi-text\">\n                        <h2 class=\"dipi-hover-box-heading\">\u30b0\u30eb\u30fc\u30d7\u306e\u53c2\u52a0\u8005<\/h2>\n                        \n                    <\/div>\n              <\/div>\n            <\/div>\n            \n                    <div class=\"dipi-hover-box-hover\">\n                \n                <div class=\"dipi-hover-box-hover-innner\">\n                    \n                    <div class=\"dipi-text\">\n                        \n                        <div class=\"dipi-desc\"><p>3\u540d\u304b\u3089\u6700\u59274\u540d\u307e\u3067\u306e\u5c11\u4eba\u6570\u30b0\u30eb\u30fc\u30d7<\/p><\/div>\n                    <\/div>\n                    <a class=\"et_pb_button dipi-hover-button\" href=\"#\">Learn More<\/a>\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_9 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_8_24 et_flex_column_8_24_tablet et_flex_column_24_24_phone\">\n<div class=\"dipi_hover_box_5 dipi_hover_box et_pb_module\"><div class=\"dipi-hover-box-container dipi-hover-box-slide-top hover_box_align_front_center hover_box_align_back_center\" data-force_square=\"off\">\n                <div class=\"dipi-hover-box-inner-wrapper\">\n                    <div class=\"dipi-hover-box-content\">\n              \n              <div class=\"dipi-hover-box-content-innner\">\n                    <div class=\"dipi-content-image-icon-wrap dipi-icon-wrap\">\n                    <span class=\"et-pb-icon et-pb-font-icon dipi-hover-box-content-icon\">\uf153<\/span>\n                <\/div>\n                    <div class=\"dipi-text\">\n                        <h2 class=\"dipi-hover-box-heading\">\u4fa1\u683c\u3068\u65e5\u7a0b<\/h2>\n                        \n                    <\/div>\n              <\/div>\n            <\/div>\n            \n                    <div class=\"dipi-hover-box-hover\">\n                \n                <div class=\"dipi-hover-box-hover-innner\">\n                    \n                    <div class=\"dipi-text\">\n                        \n                        <div class=\"dipi-desc\"><p>1\u9031\u9593 1,980\u30e6\u30fc\u30ed | \u90e8\u54c1\u4ee3\u5225\u9014 | \u30c9\u30a4\u30c4\u4ed8\u52a0\u4fa1\u5024\u7a0e19%<\/p>\n<p>2026\u5e745\u67084\u65e5\uff5e8\u65e5\uff08\u6e80\u5e2d\uff09<br \/>2026\u5e7410\u670826\u65e5\uff5e30\u65e5<br \/>2026\u5e7411\u670823\u65e5\uff5e27\u65e5<br \/>\u8ffd\u52a0\u65e5\u7a0b\u306f\u500b\u5225\u306b\u624b\u914d\u53ef\u80fd<\/p><\/div>\n                    <\/div>\n                    <a class=\"et_pb_button dipi-hover-button\" href=\"#\">Learn More<\/a>\n                <\/div>\n            <\/div>\n                <\/div>\n            <\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_5 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_10 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_heading_1 et_pb_heading et_pb_module et_flex_module\"><div class=\"et_pb_heading_container\"><h1 class=\"et_pb_module_header\">\u30bb\u30df\u30ca\u30fc\u306e\u8a73\u7d30\u5185\u5bb9<\/h1><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_6 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_11 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_image_1 et_pb_image et_pb_module et_flex_module\"><span class=\"et_pb_image_wrap\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/piano-academy-fritz.com\/wp-content\/uploads\/2026\/02\/1-1-1024x768.jpeg\" title=\"1\" width=\"1024\" height=\"768\" srcset=\"https:\/\/piano-academy-fritz.com\/wp-content\/uploads\/2026\/02\/1-1-980x735.jpeg 980w, https:\/\/piano-academy-fritz.com\/wp-content\/uploads\/2026\/02\/1-1-480x360.jpeg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" class=\"wp-image-27747046\" \/><\/span><\/div>\n<\/div>\n\n<div class=\"et_pb_column_12 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_12_24 et_flex_column_24_24_tablet et_flex_column_24_24_phone\">\n<div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module\"><div class=\"et_pb_text_inner\"><ul>\n<li>\u65b0\u3057\u3044\u30ef\u30a4\u30e4\u30fc\u3092\u4f7f\u7528\u3057\u305f\u30c0\u30f3\u30d1\u30fc\u30b7\u30b9\u30c6\u30e0\u306e\u53d6\u308a\u4ed8\u3051\u3068\u3001\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\u57fa\u6e96\u3078\u306e\u8abf\u6574<\/li>\n<li>\u30c0\u30f3\u30d1\u30fc\u30c8\u30ec\u30a4\u306e\u4fee\u7406\u3068\u30dd\u30b8\u30b7\u30e7\u30cb\u30f3\u30b0\uff08\u65b0\u65e7\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\uff09\u3001\u304a\u3088\u3073\u30ad\u30fc\u30a8\u30f3\u30c9\u30d5\u30a7\u30eb\u30c8\u306e\u4fee\u7406<\/li>\n<li>\u30c0\u30f3\u30d1\u30fc\u30b7\u30b9\u30c6\u30e0\u306e\u4e16\u4ee3\u306b\u3088\u308b\u9055\u3044\u3001\u30ac\u30a4\u30c9\u30ec\u30fc\u30eb\u306e\u4fee\u7406\u65b9\u6cd5\u3001\u304a\u3088\u3073\u65b0\u3057\u3044\u30c0\u30f3\u30d1\u30fc\u30ac\u30a4\u30c9\u30ec\u30fc\u30eb\u306e\u88fd\u4f5c\u3068\u53d6\u308a\u4ed8\u3051\u65b9\u6cd5\u306b\u3064\u3044\u3066\u5b66\u3076<\/li>\n<li>\u30c0\u30f3\u30d1\u30fc\u30d5\u30a7\u30eb\u30c8\u3068\u30ef\u30a4\u30e4\u30fc\u3092\u3044\u3064\u3001\u306a\u305c\u3001\u3069\u306e\u3088\u3046\u306b\u4ea4\u63db\u3059\u3079\u304d\u304b\u3092\u5b66\u3076<\/li>\n<li>\u5fc5\u8981\u306a\u5de5\u5177\u3068\u6750\u6599\u306e\u7279\u5b9a<\/li>\n<li>\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\u57fa\u6e96\u306b\u6cbf\u3063\u305f\u6b63\u3057\u3044\u30c0\u30f3\u30d1\u30fc\u8abf\u6574<\/li>\n<li>\u300c\u30cf\u30fc\u30d5\u30da\u30c0\u30eb\u300d\u594f\u6cd5\u306e\u305f\u3081\u306e\u30c0\u30f3\u30d1\u30fc\u6a5f\u80fd<\/li>\n<li>\u30a6\u30ca\u30b3\u30eb\u30c0\u4f7f\u7528\u6642\u306e\u30ce\u30a4\u30ba\u3078\u306e\u5bfe\u51e6\u3001\u304a\u3088\u3073\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\u7279\u6709\u306e\u30c0\u30f3\u30d1\u30fc\u30ce\u30a4\u30ba\u3084\u6b8b\u97ff\u306e\u4f4e\u6e1b<\/li>\n<li>\u30b3\u30f3\u30b5\u30fc\u30c8\u6f14\u594f\u3084\u30ec\u30b3\u30fc\u30c7\u30a3\u30f3\u30b0\u306e\u8981\u6c42\u306b\u5fdc\u3058\u305f\u30c0\u30f3\u30d1\u30fc\u30b7\u30b9\u30c6\u30e0\u306e\u6e96\u5099<\/li>\n<li>\u30b3\u30f3\u30c8\u30ed\u30fc\u30eb\u3055\u308c\u305f\u30ec\u30ac\u30fc\u30c8\u8a2d\u5b9a<\/li>\n<li>\u30bd\u30b9\u30c6\u30cc\u30fc\u30c8\u306e\u53d6\u308a\u4ed8\u3051\u3068\u9069\u5207\u306a\u8abf\u6574<\/li>\n<li>\u6b63\u3057\u3044\u30c8\u30e9\u30c3\u30d7\u30ef\u30fc\u30af\u306e\u8abf\u6574<\/li>\n<\/ul>\n<\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_light et_pb_module et_flex_module\" href=\"https:\/\/piano-academy-fritz.com\/contact-piano-academy-fritz\/\">\u4eca\u3059\u3050\u304a\u554f\u3044\u5408\u308f\u305b\u304f\u3060\u3055\u3044<\/a><\/div>\n<\/div>\n<\/div>\n<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"dipi_cpt_category":[],"class_list":["post-27748929","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Piano Academy Fritz\u306b\u304a\u3051\u308b\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\u30fb\u30a2\u30af\u30b7\u30e7\u30f3\u8abf\u6574\u30bb\u30df\u30ca\u30fc - Piano Academy Fritz | Steinway<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/piano-academy-fritz.com\/ja\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piano Academy Fritz\u306b\u304a\u3051\u308b\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\u30fb\u30a2\u30af\u30b7\u30e7\u30f3\u8abf\u6574\u30bb\u30df\u30ca\u30fc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/piano-academy-fritz.com\/ja\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\/\" \/>\n<meta property=\"og:site_name\" content=\"Piano Academy Fritz | Steinway\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-11T16:29:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/piano-academy-fritz.com\\\/ja\\\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\\\/\",\"url\":\"https:\\\/\\\/piano-academy-fritz.com\\\/ja\\\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\\\/\",\"name\":\"Piano Academy Fritz\u306b\u304a\u3051\u308b\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\u30fb\u30a2\u30af\u30b7\u30e7\u30f3\u8abf\u6574\u30bb\u30df\u30ca\u30fc - Piano Academy Fritz | Steinway\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/piano-academy-fritz.com\\\/ja\\\/#website\"},\"datePublished\":\"2026-02-11T06:54:04+00:00\",\"dateModified\":\"2026-03-11T16:29:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/piano-academy-fritz.com\\\/ja\\\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/piano-academy-fritz.com\\\/ja\\\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/piano-academy-fritz.com\\\/ja\\\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/piano-academy-fritz.com\\\/ja\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piano Academy Fritz\u306b\u304a\u3051\u308b\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\u30fb\u30a2\u30af\u30b7\u30e7\u30f3\u8abf\u6574\u30bb\u30df\u30ca\u30fc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/piano-academy-fritz.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/piano-academy-fritz.com\\\/ja\\\/\",\"name\":\"Piano Academy Fritz | Steinway\",\"description\":\"Masterclasses For Piano Technicians\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/piano-academy-fritz.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Piano Academy Fritz\u306b\u304a\u3051\u308b\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\u30fb\u30a2\u30af\u30b7\u30e7\u30f3\u8abf\u6574\u30bb\u30df\u30ca\u30fc - Piano Academy Fritz | Steinway","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/piano-academy-fritz.com\/ja\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\/","og_locale":"ja_JP","og_type":"article","og_title":"Piano Academy Fritz\u306b\u304a\u3051\u308b\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\u30fb\u30a2\u30af\u30b7\u30e7\u30f3\u8abf\u6574\u30bb\u30df\u30ca\u30fc","og_url":"https:\/\/piano-academy-fritz.com\/ja\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\/","og_site_name":"Piano Academy Fritz | Steinway","article_modified_time":"2026-03-11T16:29:30+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/piano-academy-fritz.com\/ja\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\/","url":"https:\/\/piano-academy-fritz.com\/ja\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\/","name":"Piano Academy Fritz\u306b\u304a\u3051\u308b\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\u30fb\u30a2\u30af\u30b7\u30e7\u30f3\u8abf\u6574\u30bb\u30df\u30ca\u30fc - Piano Academy Fritz | Steinway","isPartOf":{"@id":"https:\/\/piano-academy-fritz.com\/ja\/#website"},"datePublished":"2026-02-11T06:54:04+00:00","dateModified":"2026-03-11T16:29:30+00:00","breadcrumb":{"@id":"https:\/\/piano-academy-fritz.com\/ja\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/piano-academy-fritz.com\/ja\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/piano-academy-fritz.com\/ja\/piano-academy-fritz%e3%81%ab%e3%81%8a%e3%81%91%e3%82%8b%e3%82%b9%e3%82%bf%e3%82%a4%e3%83%b3%e3%82%a6%e3%82%a7%e3%82%a4%e3%83%bb%e3%82%a2%e3%82%af%e3%82%b7%e3%83%a7%e3%83%b3%e8%aa%bf%e6%95%b4%e3%82%bb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/piano-academy-fritz.com\/ja\/"},{"@type":"ListItem","position":2,"name":"Piano Academy Fritz\u306b\u304a\u3051\u308b\u30b9\u30bf\u30a4\u30f3\u30a6\u30a7\u30a4\u30fb\u30a2\u30af\u30b7\u30e7\u30f3\u8abf\u6574\u30bb\u30df\u30ca\u30fc"}]},{"@type":"WebSite","@id":"https:\/\/piano-academy-fritz.com\/ja\/#website","url":"https:\/\/piano-academy-fritz.com\/ja\/","name":"Piano Academy Fritz | Steinway","description":"Masterclasses For Piano Technicians","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/piano-academy-fritz.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"}]}},"_links":{"self":[{"href":"https:\/\/piano-academy-fritz.com\/ja\/wp-json\/wp\/v2\/pages\/27748929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/piano-academy-fritz.com\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/piano-academy-fritz.com\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/piano-academy-fritz.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/piano-academy-fritz.com\/ja\/wp-json\/wp\/v2\/comments?post=27748929"}],"version-history":[{"count":0,"href":"https:\/\/piano-academy-fritz.com\/ja\/wp-json\/wp\/v2\/pages\/27748929\/revisions"}],"wp:attachment":[{"href":"https:\/\/piano-academy-fritz.com\/ja\/wp-json\/wp\/v2\/media?parent=27748929"}],"wp:term":[{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/piano-academy-fritz.com\/ja\/wp-json\/wp\/v2\/dipi_cpt_category?post=27748929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}